{"id":1873,"count":1,"description":"","link":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl","name":"flamencotablao in Ayamonte","slug":"flamencotablao-ayamonte-nl","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>flamencotablao in Ayamonte Archives | Tablaos Flamencos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"flamencotablao in Ayamonte archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl\" \/>\n<meta property=\"og:site_name\" content=\"Tablaos Flamencos\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tablaosflamencos.com\/wp-content\/uploads\/que-es-un-tablao-flamenco-y-como-elegir-el-adecuado-guia-practica-01.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tablaosflamenco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl\",\"url\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl\",\"name\":\"flamencotablao in Ayamonte Archives | Tablaos Flamencos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"flamencotablao in Ayamonte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl#website\",\"url\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\",\"name\":\"Tablaos Flamencos\",\"description\":\"Entradas para tablaos flamencos de Espa\u00f1a\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl#organization\"},\"alternateName\":\"Tablaos Flamencos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Organization\",\"Place\",\"EntertainmentBusiness\"],\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl#organization\",\"name\":\"Tablaos Flamencos\",\"alternateName\":\"Tablaos Flamencos\",\"url\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tablaosflamencos\",\"https:\\\/\\\/x.com\\\/tablaosflamenco\",\"https:\\\/\\\/mastodon.social\\\/@tablaosflamencos\",\"https:\\\/\\\/www.instagram.com\\\/tablaosflamencos\",\"https:\\\/\\\/tiktok.com\\\/@tablaosflamencos\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/109408238\\\/\"],\"description\":\"Venta de entradas para espect\u00e1culos flamencos\",\"legalName\":\"Tablaos Flamencos\",\"foundingDate\":\"2015-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"address\":{\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"37.3868072\",\"longitude\":\"-5.993280299999999\"},\"telephone\":[\"+34623787787\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+34623787787\",\"email\":\"info@tablaosflamencos.com\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"info@tablaosflamencos.com\",\"priceRange\":\"$$$\",\"currenciesAccepted\":\"\u20ac\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#local-main-place-address\",\"streetAddress\":\"C\\\/ Alemanes, 19\",\"addressLocality\":\"Sevilla\",\"postalCode\":\"41004\",\"addressRegion\":\"Sevilla\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/nl\\\/tag\\\/flamencotablao-ayamonte-nl#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/wp-content\\\/uploads\\\/tablaos-flamencos-06-3.webp\",\"contentUrl\":\"https:\\\/\\\/www.tablaosflamencos.com\\\/wp-content\\\/uploads\\\/tablaos-flamencos-06-3.webp\",\"width\":600,\"height\":620,\"caption\":\"Tablaos Flamencos\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Sevilla\" \/>\n<meta name=\"geo.position\" content=\"37.3868072;-5.993280299999999\" \/>\n<meta name=\"geo.region\" content=\"Spanje\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"flamencotablao in Ayamonte Archives | Tablaos Flamencos","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"flamencotablao in Ayamonte archivos","og_url":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl","og_site_name":"Tablaos Flamencos","og_image":[{"width":1920,"height":1072,"url":"https:\/\/www.tablaosflamencos.com\/wp-content\/uploads\/que-es-un-tablao-flamenco-y-como-elegir-el-adecuado-guia-practica-01.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@tablaosflamenco","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl","url":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl","name":"flamencotablao in Ayamonte Archives | Tablaos Flamencos","isPartOf":{"@id":"https:\/\/www.tablaosflamencos.com\/nl#website"},"breadcrumb":{"@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tablaosflamencos.com\/nl"},{"@type":"ListItem","position":2,"name":"flamencotablao in Ayamonte"}]},{"@type":"WebSite","@id":"https:\/\/www.tablaosflamencos.com\/nl#website","url":"https:\/\/www.tablaosflamencos.com\/nl","name":"Tablaos Flamencos","description":"Entradas para tablaos flamencos de Espa\u00f1a","publisher":{"@id":"https:\/\/www.tablaosflamencos.com\/nl#organization"},"alternateName":"Tablaos Flamencos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tablaosflamencos.com\/nl?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Organization","Place","EntertainmentBusiness"],"@id":"https:\/\/www.tablaosflamencos.com\/nl#organization","name":"Tablaos Flamencos","alternateName":"Tablaos Flamencos","url":"https:\/\/www.tablaosflamencos.com\/nl","logo":{"@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/tablaosflamencos","https:\/\/x.com\/tablaosflamenco","https:\/\/mastodon.social\/@tablaosflamencos","https:\/\/www.instagram.com\/tablaosflamencos","https:\/\/tiktok.com\/@tablaosflamencos","https:\/\/www.linkedin.com\/company\/109408238\/"],"description":"Venta de entradas para espect\u00e1culos flamencos","legalName":"Tablaos Flamencos","foundingDate":"2015-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"address":{"@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"37.3868072","longitude":"-5.993280299999999"},"telephone":["+34623787787"],"contactPoint":{"@type":"ContactPoint","telephone":"+34623787787","email":"info@tablaosflamencos.com"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"info@tablaosflamencos.com","priceRange":"$$$","currenciesAccepted":"\u20ac"},{"@type":"PostalAddress","@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#local-main-place-address","streetAddress":"C\/ Alemanes, 19","addressLocality":"Sevilla","postalCode":"41004","addressRegion":"Sevilla","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.tablaosflamencos.com\/nl\/tag\/flamencotablao-ayamonte-nl#local-main-organization-logo","url":"https:\/\/www.tablaosflamencos.com\/wp-content\/uploads\/tablaos-flamencos-06-3.webp","contentUrl":"https:\/\/www.tablaosflamencos.com\/wp-content\/uploads\/tablaos-flamencos-06-3.webp","width":600,"height":620,"caption":"Tablaos Flamencos"}]},"geo.placename":"Sevilla","geo.position":{"lat":"37.3868072","long":"-5.993280299999999"},"geo.region":"Spanje"},"_links":{"self":[{"href":"https:\/\/www.tablaosflamencos.com\/nl\/wp-json\/wp\/v2\/tags\/1873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tablaosflamencos.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.tablaosflamencos.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.tablaosflamencos.com\/nl\/wp-json\/wp\/v2\/posts?tags=1873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}